{"id":19155,"date":"2019-10-28T19:18:18","date_gmt":"2019-10-28T19:18:18","guid":{"rendered":"https:\/\/www.eliassen.nl\/?product=fotoschilderij-op-canvas-114x80cm-skyline"},"modified":"2026-01-07T12:10:05","modified_gmt":"2026-01-07T11:10:05","slug":"fotoschilderij-op-canvas-114x80cm-skyline","status":"publish","type":"product","link":"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/","title":{"rendered":"Fotoschilderij op canvas 114x80cm Skyline"},"content":{"rendered":"<p>Een verrijking voor in uw huis, deze haarscherpe foto van Manhattan, die gedrukt is op sterk canvas. Foto loopt ook door over de zijkanten. Canvas is gespannen op een sterk 4,7cm dik houten frame, met verstevigend kruis in het midden,\u00a0kromtrekken komt daardoor niet voor. Simpel op te hangen met een schroefje.<br \/>\n<strong>We hebben nagenoeg de gehele collectie van deze shop ook in de zaak, kom dus gerust deze collectie bij ons bekijken. Wilt u komen kijken voor \u00e9\u00e9n speciaal model, bel of mail ons dan even aub.<\/strong><\/p>\n<ul>\n<li>Maat: 114 x 80cm.<\/li>\n<li>Dik houten frame.<\/li>\n<li>Snel geleverd.<\/li>\n<li>Alleen voor binnen.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Een verrijking voor in uw huis, deze haarscherpe foto van Manhattan, die gedrukt is op sterk canvas. Foto loopt ook door over de zijkanten. Canvas is gespannen op een sterk 4,7cm dik houten frame, met verstevigend kruis in het midden,\u00a0kromtrekken komt daardoor niet voor. Simpel op te hangen met een schroefje. We hebben nagenoeg de &hellip;<\/p>\n","protected":false},"featured_media":19158,"template":"","meta":{"_acf_changed":false,"_genesis_title":"","_genesis_description":""},"product_brand":[7504],"product_cat":[475,409,412],"product_tag":[],"class_list":["post-19155","product","type-product","status-publish","has-post-thumbnail","product_brand-overig","product_cat-canvas-schilderijen","product_cat-schilderijen","product_cat-schilderijen-outlet","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"meta_all":{"total_sales":"0","searchwp_related":"fotoschilderij canvas 114x80cm skyline canvas 114x80cm","cor_restricted_countries":[],"cor_product_price_text_product_level":"","cor_add_text":"","cor_hide_r_add_cart_product_level":"1","cor_product_price_cart_btn_product_level":"","cor_replace_add_to_cart_custom_btn_product_level":"","enbility_product_level_disability":" ","enbility_product_level_exclude_visibility_rules":" "},"meta_all_flat":{"total_sales":"0","searchwp_related":"fotoschilderij canvas 114x80cm skyline canvas 114x80cm","cor_product_price_text_product_level":"","cor_add_text":"","cor_hide_r_add_cart_product_level":"1","cor_product_price_cart_btn_product_level":"","cor_replace_add_to_cart_custom_btn_product_level":"","enbility_product_level_disability":" ","enbility_product_level_exclude_visibility_rules":" "},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fotoschilderij op canvas 114x80cm Skyline | Eliassen<\/title>\n<meta name=\"description\" content=\"Bij Eliassen koopt u Fotoschilderij op canvas 114x80cm Skyline online of live te bekijken in de showroom. Bestel direct online.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Overig Fotoschilderij op canvas 114x80cm Skyline - Eliassen.nl\" \/>\n<meta property=\"og:description\" content=\"Bij Eliassen koopt u Fotoschilderij op canvas 114x80cm Skyline online of live te bekijken in de showroom. Bestel direct online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/\" \/>\n<meta property=\"og:site_name\" content=\"Eliassen.nl\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-07T11:10:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/canvas08011424114x80cm.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"749\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/fotoschilderij-op-canvas-114x80cm-skyline\\\/\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/fotoschilderij-op-canvas-114x80cm-skyline\\\/\",\"name\":\"Fotoschilderij op canvas 114x80cm Skyline | Eliassen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/fotoschilderij-op-canvas-114x80cm-skyline\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/fotoschilderij-op-canvas-114x80cm-skyline\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/canvas08011424114x80cm.jpg\",\"datePublished\":\"2019-10-28T19:18:18+00:00\",\"dateModified\":\"2026-01-07T11:10:05+00:00\",\"description\":\"Bij Eliassen koopt u Fotoschilderij op canvas 114x80cm Skyline online of live te bekijken in de showroom. Bestel direct online.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/fotoschilderij-op-canvas-114x80cm-skyline\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/fotoschilderij-op-canvas-114x80cm-skyline\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/fotoschilderij-op-canvas-114x80cm-skyline\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/canvas08011424114x80cm.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/canvas08011424114x80cm.jpg\",\"width\":1024,\"height\":749,\"caption\":\"canvas080114-24-114x80cm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/fotoschilderij-op-canvas-114x80cm-skyline\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Winkel\",\"item\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/winkel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schilderijen\",\"item\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/schilderijen\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Canvas schilderijen\",\"item\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/schilderijen\\\/canvas-schilderijen\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Fotoschilderij op canvas 114x80cm Skyline\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/\",\"name\":\"Eliassen Home & Garden Pleasure\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/#organization\"},\"alternateName\":\"Eliassen.nl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/#organization\",\"name\":\"Eliassen Home & Garden Pleasure\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/fotoschilderij-op-canvas-114x80cm-skyline\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/fotoschilderij-op-canvas-114x80cm-skyline\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TuincentrumEliassenAmmerzoden\",\"https:\\\/\\\/www.instagram.com\\\/eliassenhomeandgarden\\\/\",\"https:\\\/\\\/nl.pinterest.com\\\/eliassenhomeandgarden\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@eliassenhomegardenpleasure4558\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/nl\\\/fotoschilderij-op-canvas-114x80cm-skyline\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo_4nd.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo_4nd.jpg\",\"width\":500,\"height\":500,\"caption\":\"Eliassen Home & Garden Pleasure\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"30.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"Canvas080114-24\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fotoschilderij op canvas 114x80cm Skyline | Eliassen","description":"Bij Eliassen koopt u Fotoschilderij op canvas 114x80cm Skyline online of live te bekijken in de showroom. Bestel direct online.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/","og_locale":"nl_NL","og_type":"article","og_title":"Overig Fotoschilderij op canvas 114x80cm Skyline - Eliassen.nl","og_description":"Bij Eliassen koopt u Fotoschilderij op canvas 114x80cm Skyline online of live te bekijken in de showroom. Bestel direct online.","og_url":"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/","og_site_name":"Eliassen.nl","article_publisher":"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","article_modified_time":"2026-01-07T11:10:05+00:00","og_image":[{"width":1024,"height":749,"url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/canvas08011424114x80cm.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/","url":"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/","name":"Fotoschilderij op canvas 114x80cm Skyline | Eliassen","isPartOf":{"@id":"https:\/\/www.eliassen.nl\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/#primaryimage"},"image":{"@id":"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/canvas08011424114x80cm.jpg","datePublished":"2019-10-28T19:18:18+00:00","dateModified":"2026-01-07T11:10:05+00:00","description":"Bij Eliassen koopt u Fotoschilderij op canvas 114x80cm Skyline online of live te bekijken in de showroom. Bestel direct online.","breadcrumb":{"@id":"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/#primaryimage","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/canvas08011424114x80cm.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/canvas08011424114x80cm.jpg","width":1024,"height":749,"caption":"canvas080114-24-114x80cm"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eliassen.nl\/nl\/"},{"@type":"ListItem","position":2,"name":"Winkel","item":"https:\/\/www.eliassen.nl\/nl\/winkel\/"},{"@type":"ListItem","position":3,"name":"Schilderijen","item":"https:\/\/www.eliassen.nl\/nl\/schilderijen\/"},{"@type":"ListItem","position":4,"name":"Canvas schilderijen","item":"https:\/\/www.eliassen.nl\/nl\/schilderijen\/canvas-schilderijen\/"},{"@type":"ListItem","position":5,"name":"Fotoschilderij op canvas 114x80cm Skyline"}]},{"@type":"WebSite","@id":"https:\/\/www.eliassen.nl\/nl\/#website","url":"https:\/\/www.eliassen.nl\/nl\/","name":"Eliassen Home & Garden Pleasure","description":"","publisher":{"@id":"https:\/\/www.eliassen.nl\/nl\/#organization"},"alternateName":"Eliassen.nl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eliassen.nl\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":["Organization","Place"],"@id":"https:\/\/www.eliassen.nl\/nl\/#organization","name":"Eliassen Home & Garden Pleasure","url":"https:\/\/www.eliassen.nl\/nl\/","logo":{"@id":"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","https:\/\/www.instagram.com\/eliassenhomeandgarden\/","https:\/\/nl.pinterest.com\/eliassenhomeandgarden\/","https:\/\/www.youtube.com\/@eliassenhomegardenpleasure4558"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.eliassen.nl\/nl\/fotoschilderij-op-canvas-114x80cm-skyline\/#local-main-organization-logo","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","width":500,"height":500,"caption":"Eliassen Home & Garden Pleasure"}]},"product_price_amount":"30.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"Canvas080114-24","product_condition":"new"},"df_price":30,"df_sale_price":30,"df_regular_price":65,"df_image_link":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/canvas08011424114x80cm.jpg","image":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/canvas08011424114x80cm.jpg","price_search":"<span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>&nbsp;30,00<\/bdi><\/span>","category":"Canvas schilderijen","global_unique_id":"7438245735716","sku":"7438245735716 \/ Canvas080114-24","_links":{"self":[{"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/product\/19155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/media\/19158"}],"wp:attachment":[{"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/media?parent=19155"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/product_brand?post=19155"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/product_cat?post=19155"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/product_tag?post=19155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}