{"id":172098,"date":"2025-01-29T10:24:02","date_gmt":"2025-01-29T09:24:02","guid":{"rendered":"https:\/\/www.eliassen.nl\/?post_type=product&#038;p=172098"},"modified":"2026-01-12T20:17:42","modified_gmt":"2026-01-12T19:17:42","slug":"bolvaas-metaal-pioen-bruin-wit-49cm","status":"publish","type":"product","link":"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/","title":{"rendered":"Bolvaas metaal Pioen grijs goud 49cm"},"content":{"rendered":"<p>Bent u opzoek naar een mooi en unieke vaas? Ga voor een metalen vaas! Onze serie aan metalen vazen met diverse bloemen en versieringen in meerdere kleuren is een vrolijke toevoeging voor in uw interieur.<\/p>\n<p>Dit model met pioenrozen is in het zwart wit gekleurd met gouden details.<\/p>\n<p>Deze potten en vazen zijn zorgvuldig waterdicht gemaakt van metaal, met daar overheen de prachtige kleuren transfer.<\/p>\n<p>Ondanks dat deze pottenserie waterdicht is, wordt er toch geadviseerd om een waterdichte passende pot of vaas in de overpot te plaatsen waarin de verse bloemen komen, om roestvorming te voorkomen. Het spreekt voor zich dat dit natuurlijk niet nodig is met zijde bloemen.<\/p>\n<p>Kom gerust live bij ons kijken naar deze serie in onze showroom!<\/p>\n<ul>\n<li>Afmetingen: 43x49cm hoog<\/li>\n<li>Niet voor buiten gebruik<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u2713 43x49cm \u2713 Countryfield \u2713 ongeveer 5kg<\/p>\n","protected":false},"featured_media":172099,"template":"","meta":{"_acf_changed":false,"_genesis_title":"","_genesis_description":""},"product_brand":[6866],"product_cat":[7031],"product_tag":[],"class_list":{"0":"post-172098","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-countryfield","7":"product_cat-metalen-potten-en-vazen","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"meta_all":{"cor_restricted_countries":[],"cor_product_price_text_product_level":"","cor_add_text":"","cor_hide_r_add_cart_product_level":"1","cor_product_price_cart_btn_product_level":"","cor_replace_add_to_cart_custom_btn_product_level":"","enbility_product_level_disability":" ","enbility_product_level_exclude_visibility_rules":" ","total_sales":"1","searchwp_related":"bolvaas metaal pioen bruin wit 49cm wit 49cm","wpseo_global_identifier_values":{"gtin8":"","gtin12":"","gtin13":"","gtin14":"","isbn":"","mpn":""}},"meta_all_flat":{"cor_product_price_text_product_level":"","cor_add_text":"","cor_hide_r_add_cart_product_level":"1","cor_product_price_cart_btn_product_level":"","cor_replace_add_to_cart_custom_btn_product_level":"","enbility_product_level_disability":" ","enbility_product_level_exclude_visibility_rules":" ","total_sales":"1","searchwp_related":"bolvaas metaal pioen bruin wit 49cm wit 49cm","wpseo_global_identifier_values.gtin8":"","wpseo_global_identifier_values.gtin12":"","wpseo_global_identifier_values.gtin13":"","wpseo_global_identifier_values.gtin14":"","wpseo_global_identifier_values.isbn":"","wpseo_global_identifier_values.mpn":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Countryfield Bolvaas metaal Pioen grijs goud 49cm - Eliassen.nl<\/title>\n<meta name=\"description\" content=\"Op zoek naar een prachtige, unieke vaas? Dit prachtige, metalen model met pioenrozen in zwart wit kleuren en gouden details zult u zeker waarderen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Countryfield Bolvaas metaal Pioen grijs goud 49cm - Eliassen.nl\" \/>\n<meta property=\"og:description\" content=\"Op zoek naar een prachtige, unieke vaas? Dit prachtige, metalen model met pioenrozen in zwart wit kleuren en gouden details zult u zeker waarderen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/\" \/>\n<meta property=\"og:site_name\" content=\"Eliassen.nl\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-12T19:17:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2025\/01\/Bolvaas-metaal-groot-bruin-Eliassen.nl-817008.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2362\" \/>\n\t<meta property=\"og:image:height\" content=\"1575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/\",\"url\":\"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/\",\"name\":\"Countryfield Bolvaas metaal Pioen grijs goud 49cm - Eliassen.nl\",\"isPartOf\":{\"@id\":\"https:\/\/www.eliassen.nl\/nl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2025\/01\/Bolvaas-metaal-groot-bruin-Eliassen.nl-817008.jpg\",\"datePublished\":\"2025-01-29T09:24:02+00:00\",\"dateModified\":\"2026-01-12T19:17:42+00:00\",\"description\":\"Op zoek naar een prachtige, unieke vaas? Dit prachtige, metalen model met pioenrozen in zwart wit kleuren en gouden details zult u zeker waarderen.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#primaryimage\",\"url\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2025\/01\/Bolvaas-metaal-groot-bruin-Eliassen.nl-817008.jpg\",\"contentUrl\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2025\/01\/Bolvaas-metaal-groot-bruin-Eliassen.nl-817008.jpg\",\"width\":2362,\"height\":1575},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eliassen.nl\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Winkel\",\"item\":\"https:\/\/www.eliassen.nl\/nl\/winkel\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Metalen potten en vazen\",\"item\":\"https:\/\/www.eliassen.nl\/nl\/product-categorie\/bloempotten-en-bloembakken\/metalen-potten-en-vazen\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Bolvaas metaal Pioen grijs goud 49cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eliassen.nl\/nl\/#website\",\"url\":\"https:\/\/www.eliassen.nl\/nl\/\",\"name\":\"Eliassen Home & Garden Pleasure\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.eliassen.nl\/nl\/#organization\"},\"alternateName\":\"Eliassen.nl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eliassen.nl\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/www.eliassen.nl\/nl\/#organization\",\"name\":\"Eliassen Home & Garden Pleasure\",\"url\":\"https:\/\/www.eliassen.nl\/nl\/\",\"logo\":{\"@id\":\"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden\",\"https:\/\/www.instagram.com\/eliassenhomeandgarden\/\",\"https:\/\/nl.pinterest.com\/eliassenhomeandgarden\/\",\"https:\/\/www.youtube.com\/@eliassenhomegardenpleasure4558\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#local-main-organization-logo\",\"url\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg\",\"contentUrl\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg\",\"width\":500,\"height\":500,\"caption\":\"Eliassen Home & Garden Pleasure\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"189.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"817008\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Countryfield Bolvaas metaal Pioen grijs goud 49cm - Eliassen.nl","description":"Op zoek naar een prachtige, unieke vaas? Dit prachtige, metalen model met pioenrozen in zwart wit kleuren en gouden details zult u zeker waarderen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/","og_locale":"nl_NL","og_type":"article","og_title":"Countryfield Bolvaas metaal Pioen grijs goud 49cm - Eliassen.nl","og_description":"Op zoek naar een prachtige, unieke vaas? Dit prachtige, metalen model met pioenrozen in zwart wit kleuren en gouden details zult u zeker waarderen.","og_url":"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/","og_site_name":"Eliassen.nl","article_publisher":"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","article_modified_time":"2026-01-12T19:17:42+00:00","og_image":[{"width":2362,"height":1575,"url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2025\/01\/Bolvaas-metaal-groot-bruin-Eliassen.nl-817008.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/","url":"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/","name":"Countryfield Bolvaas metaal Pioen grijs goud 49cm - Eliassen.nl","isPartOf":{"@id":"https:\/\/www.eliassen.nl\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#primaryimage"},"image":{"@id":"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2025\/01\/Bolvaas-metaal-groot-bruin-Eliassen.nl-817008.jpg","datePublished":"2025-01-29T09:24:02+00:00","dateModified":"2026-01-12T19:17:42+00:00","description":"Op zoek naar een prachtige, unieke vaas? Dit prachtige, metalen model met pioenrozen in zwart wit kleuren en gouden details zult u zeker waarderen.","breadcrumb":{"@id":"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#primaryimage","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2025\/01\/Bolvaas-metaal-groot-bruin-Eliassen.nl-817008.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2025\/01\/Bolvaas-metaal-groot-bruin-Eliassen.nl-817008.jpg","width":2362,"height":1575},{"@type":"BreadcrumbList","@id":"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eliassen.nl\/nl\/"},{"@type":"ListItem","position":2,"name":"Winkel","item":"https:\/\/www.eliassen.nl\/nl\/winkel\/"},{"@type":"ListItem","position":3,"name":"Metalen potten en vazen","item":"https:\/\/www.eliassen.nl\/nl\/product-categorie\/bloempotten-en-bloembakken\/metalen-potten-en-vazen\/"},{"@type":"ListItem","position":4,"name":"Bolvaas metaal Pioen grijs goud 49cm"}]},{"@type":"WebSite","@id":"https:\/\/www.eliassen.nl\/nl\/#website","url":"https:\/\/www.eliassen.nl\/nl\/","name":"Eliassen Home & Garden Pleasure","description":"","publisher":{"@id":"https:\/\/www.eliassen.nl\/nl\/#organization"},"alternateName":"Eliassen.nl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eliassen.nl\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":["Organization","Place"],"@id":"https:\/\/www.eliassen.nl\/nl\/#organization","name":"Eliassen Home & Garden Pleasure","url":"https:\/\/www.eliassen.nl\/nl\/","logo":{"@id":"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","https:\/\/www.instagram.com\/eliassenhomeandgarden\/","https:\/\/nl.pinterest.com\/eliassenhomeandgarden\/","https:\/\/www.youtube.com\/@eliassenhomegardenpleasure4558"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.eliassen.nl\/nl\/bolvaas-metaal-pioen-bruin-wit-49cm\/#local-main-organization-logo","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","width":500,"height":500,"caption":"Eliassen Home & Garden Pleasure"}]},"product_price_amount":"189.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"817008","product_condition":"new"},"df_price":189,"df_sale_price":"","df_regular_price":189,"df_image_link":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2025\/01\/Bolvaas-metaal-groot-bruin-Eliassen.nl-817008-300x200.jpg","image":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2025\/01\/Bolvaas-metaal-groot-bruin-Eliassen.nl-817008-150x150.jpg","price_search":"<span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>&nbsp;189,00<\/bdi><\/span>","category":"Metalen potten en vazen","global_unique_id":"8718318170088","sku":"8718318170088 \/ 817008","_links":{"self":[{"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/product\/172098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/media\/172099"}],"wp:attachment":[{"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/media?parent=172098"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/product_brand?post=172098"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/product_cat?post=172098"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.eliassen.nl\/nl\/wp-json\/wp\/v2\/product_tag?post=172098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}