{"id":92819,"date":"2023-08-08T14:08:57","date_gmt":"2023-08-08T14:08:57","guid":{"rendered":"https:\/\/www.eliassen.nl\/?product=bronzen-urn-tortelduifjes-75cm"},"modified":"2026-01-16T14:44:05","modified_gmt":"2026-01-16T13:44:05","slug":"bronze-urn-lovebirds-7-5cm","status":"publish","type":"product","link":"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/","title":{"rendered":"Bronze urn lovebirds 7.5cm"},"content":{"rendered":"<p>A beautifully designed bronze urn of 2 kissing birds with an ash container that can hold a portion of the cremation ash. This way you will own a beautiful memorial ornament.<\/p>\n<p>This bronze object was crafted using the so-called lost wax method.<\/p>\n<p>This is done as follows: a wax model is embedded in a refractory mass such as clay, then the wax is melted out and the mold is dried. Then bronze is cast into the resulting cavity. After cooling, the mold is dismantled and the opening through which the bronze poured into the mold is sawed off and the sculpture remains. Finally, the sculpture is finished by plugging holes, grinding away blemishes and then staining it with an acid. Larger bronze sculptures are cast in parts and then welded together, then ground smooth.<\/p>\n<p>Bronze is an alloy of copper and tin. The higher the copper content, the higher quality the bronze is. This sculpture has a minimum copper content of 75%, absolutely guaranteeing durability.<\/p>\n<p>Outdoors, bronze statues will become slightly duller in color; you can get it shiny again by maintaining it with beeswax.<\/p>\n<ul>\n<li>Size: 8x6x5.5cm high<\/li>\n<li>Material: Bronze<\/li>\n<li>Comes with certificate<\/li>\n<li>Fast delivery<\/li>\n<li><strong>Very many from this series of bronze sculptures also live to view in our store<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>8x6x5.5cm high<br \/>\nComes with certificate<\/p>\n","protected":false},"featured_media":92816,"template":"","meta":{"_acf_changed":false,"_genesis_title":"","_genesis_description":""},"product_brand":[7506],"product_cat":[615,7076,657],"product_tag":[],"class_list":{"0":"post-92819","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-other","7":"product_cat-bronze-statues","8":"product_cat-statues","9":"product_cat-urns-and-grave-decoration","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"meta_all":{"total_sales":"0","wcml_sync_hash":{"postmeta_fields":"9414e7a96b8b9e34f7ae6abef32eef40"},"attr_label_translations":[]},"meta_all_flat":{"total_sales":"0","wcml_sync_hash.postmeta_fields":"9414e7a96b8b9e34f7ae6abef32eef40"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bronze urn lovebirds 7.5cm - Eliassen Home &amp; Gardenpleasure<\/title>\n<meta name=\"description\" content=\"Would you like to purchase an urn made of bronze? This is a brown model with 2 lovebirds kissing each other.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Other Bronze urn lovebirds 7.5cm - Eliassen.nl\" \/>\n<meta property=\"og:description\" content=\"Would you like to purchase an urn made of bronze? This is a brown model with 2 lovebirds kissing each other.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/\" \/>\n<meta property=\"og:site_name\" content=\"Eliassen.nl\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-16T13:44:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/bronzenurntortelduifjeseliassennl.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/\",\"url\":\"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/\",\"name\":\"Bronze urn lovebirds 7.5cm - Eliassen Home & Gardenpleasure\",\"isPartOf\":{\"@id\":\"https:\/\/www.eliassen.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/bronzenurntortelduifjeseliassennl.jpg\",\"datePublished\":\"2023-08-08T14:08:57+00:00\",\"dateModified\":\"2026-01-16T13:44:05+00:00\",\"description\":\"Would you like to purchase an urn made of bronze? This is a brown model with 2 lovebirds kissing each other.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#breadcrumb\"},\"inLanguage\":\"en-EN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-EN\",\"@id\":\"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#primaryimage\",\"url\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/bronzenurntortelduifjeseliassennl.jpg\",\"contentUrl\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/bronzenurntortelduifjeseliassennl.jpg\",\"width\":1024,\"height\":768,\"caption\":\"bronze urn lovebirds - eliassen.nl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eliassen.nl\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\/\/www.eliassen.nl\/en\/store\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bronze statues\",\"item\":\"https:\/\/www.eliassen.nl\/en\/bronze-statues\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Urns and grave decoration\",\"item\":\"https:\/\/www.eliassen.nl\/en\/images\/bronze-statues\/urns-and-grave-decoration\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Bronze urn lovebirds 7.5cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eliassen.nl\/en\/#website\",\"url\":\"https:\/\/www.eliassen.nl\/en\/\",\"name\":\"Eliassen Home & Garden Pleasure\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.eliassen.nl\/en\/#organization\"},\"alternateName\":\"Eliassen.nl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eliassen.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-EN\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/www.eliassen.nl\/en\/#organization\",\"name\":\"Eliassen Home & Garden Pleasure\",\"url\":\"https:\/\/www.eliassen.nl\/en\/\",\"logo\":{\"@id\":\"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden\",\"https:\/\/www.instagram.com\/eliassenhomeandgarden\/\",\"https:\/\/nl.pinterest.com\/eliassenhomeandgarden\/\",\"https:\/\/www.youtube.com\/@eliassenhomegardenpleasure4558\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-EN\",\"@id\":\"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#local-main-organization-logo\",\"url\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg\",\"contentUrl\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg\",\"width\":500,\"height\":500,\"caption\":\"Eliassen Home & Garden Pleasure\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"109.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"Fv0656\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bronze urn lovebirds 7.5cm - Eliassen Home & Gardenpleasure","description":"Would you like to purchase an urn made of bronze? This is a brown model with 2 lovebirds kissing each other.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/","og_locale":"en_US","og_type":"article","og_title":"Other Bronze urn lovebirds 7.5cm - Eliassen.nl","og_description":"Would you like to purchase an urn made of bronze? This is a brown model with 2 lovebirds kissing each other.","og_url":"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/","og_site_name":"Eliassen.nl","article_publisher":"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","article_modified_time":"2026-01-16T13:44:05+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/bronzenurntortelduifjeseliassennl.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/","url":"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/","name":"Bronze urn lovebirds 7.5cm - Eliassen Home & Gardenpleasure","isPartOf":{"@id":"https:\/\/www.eliassen.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#primaryimage"},"image":{"@id":"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/bronzenurntortelduifjeseliassennl.jpg","datePublished":"2023-08-08T14:08:57+00:00","dateModified":"2026-01-16T13:44:05+00:00","description":"Would you like to purchase an urn made of bronze? This is a brown model with 2 lovebirds kissing each other.","breadcrumb":{"@id":"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#breadcrumb"},"inLanguage":"en-EN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/"]}]},{"@type":"ImageObject","inLanguage":"en-EN","@id":"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#primaryimage","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/bronzenurntortelduifjeseliassennl.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/bronzenurntortelduifjeseliassennl.jpg","width":1024,"height":768,"caption":"bronze urn lovebirds - eliassen.nl"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eliassen.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/www.eliassen.nl\/en\/store\/"},{"@type":"ListItem","position":3,"name":"Bronze statues","item":"https:\/\/www.eliassen.nl\/en\/bronze-statues\/"},{"@type":"ListItem","position":4,"name":"Urns and grave decoration","item":"https:\/\/www.eliassen.nl\/en\/images\/bronze-statues\/urns-and-grave-decoration\/"},{"@type":"ListItem","position":5,"name":"Bronze urn lovebirds 7.5cm"}]},{"@type":"WebSite","@id":"https:\/\/www.eliassen.nl\/en\/#website","url":"https:\/\/www.eliassen.nl\/en\/","name":"Eliassen Home & Garden Pleasure","description":"","publisher":{"@id":"https:\/\/www.eliassen.nl\/en\/#organization"},"alternateName":"Eliassen.nl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eliassen.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-EN"},{"@type":["Organization","Place"],"@id":"https:\/\/www.eliassen.nl\/en\/#organization","name":"Eliassen Home & Garden Pleasure","url":"https:\/\/www.eliassen.nl\/en\/","logo":{"@id":"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","https:\/\/www.instagram.com\/eliassenhomeandgarden\/","https:\/\/nl.pinterest.com\/eliassenhomeandgarden\/","https:\/\/www.youtube.com\/@eliassenhomegardenpleasure4558"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"en-EN","@id":"https:\/\/www.eliassen.nl\/en\/bronze-urn-lovebirds-7-5cm\/#local-main-organization-logo","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","width":500,"height":500,"caption":"Eliassen Home & Garden Pleasure"}]},"product_price_amount":"109.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"Fv0656","product_condition":"new"},"df_price":109,"df_sale_price":"","df_regular_price":109,"df_image_link":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/bronzenurntortelduifjeseliassennl.jpg","image":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/bronzenurntortelduifjeseliassennl.jpg","price_search":"<span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>&nbsp;109,00<\/bdi><\/span>","category":"Bronze statues","global_unique_id":"6096523557583","_links":{"self":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product\/92819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/media\/92816"}],"wp:attachment":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/media?parent=92819"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product_brand?post=92819"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product_cat?post=92819"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product_tag?post=92819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}