{"id":72968,"date":"2022-06-20T17:19:31","date_gmt":"2022-06-20T17:19:31","guid":{"rendered":"https:\/\/www.eliassen.nl\/?product=windmolen-hapiness-25cm-rode-kern"},"modified":"2025-11-27T13:59:40","modified_gmt":"2025-11-27T12:59:40","slug":"windmill-hapiness-25cm-red-core","status":"publish","type":"product","link":"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/","title":{"rendered":"Windmill Hapiness 25cm red core"},"content":{"rendered":"<p>In any garden, this red windmill will be a nice addition.<br \/>This 110cm tall model will spin in the slightest wind because the rotating parts are fitted with ball bearings.  <br \/>This cheerful windmill is fun to give or get.<br \/>The grinder is equipped with a sturdy pin so that the whole thing stands securely in any type of soil.<br \/>Comes as a kit.<br \/>Size: 25cm wide and 110cm high.  <\/p>\n<p>This wind turbine is intended to run quietly. So in strong winds or storms, it must be in the lee.<\/p>\n<ul>\n<li>Color: Red<\/li>\n<li>Material: Metal<\/li>\n<li>Fast delivery<\/li>\n<li>Own stock<\/li>\n<li>Please note that this is not a toy!<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>In any garden, this red windmill will be a nice addition.This 110cm tall model will spin in the slightest wind because the rotating parts are fitted with ball bearings. This cheerful windmill is fun to give or get.The grinder is equipped with a sturdy pin so that the whole thing stands securely in any type &hellip;<\/p>\n","protected":false},"featured_media":72965,"template":"","meta":{"_acf_changed":false,"_genesis_title":"","_genesis_description":""},"product_brand":[7506],"product_cat":[837,846],"product_tag":[],"class_list":["post-72968","product","type-product","status-publish","has-post-thumbnail","product_brand-other","product_cat-garden-plugs","product_cat-windmills","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"meta_all":{"total_sales":"0","wcml_sync_hash":{"postmeta_fields":"c1e9851edc9576829ce8980edd0320ae"},"attr_label_translations":[]},"meta_all_flat":{"total_sales":"0","wcml_sync_hash.postmeta_fields":"c1e9851edc9576829ce8980edd0320ae"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Windmill Hapiness 25cm red core - Eliassen.nl<\/title>\n<meta name=\"description\" content=\"Want to buy a metal windmill in a red color? View all of our garden stakes on the website or stop by our store. \u2713 Large collection \u2713 Good quality\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Other Windmill Hapiness 25cm red core - Eliassen.nl\" \/>\n<meta property=\"og:description\" content=\"Want to buy a metal windmill in a red color? View all of our garden stakes on the website or stop by our store. \u2713 Large collection \u2713 Good quality\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/\" \/>\n<meta property=\"og:site_name\" content=\"Eliassen.nl\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-27T12:59:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/windmolenhapiness25cmrodekerneliassennl.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"726\" \/>\n\t<meta property=\"og:image:height\" content=\"976\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/windmill-hapiness-25cm-red-core\\\/\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/windmill-hapiness-25cm-red-core\\\/\",\"name\":\"Windmill Hapiness 25cm red core - Eliassen.nl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/windmill-hapiness-25cm-red-core\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/windmill-hapiness-25cm-red-core\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/windmolenhapiness25cmrodekerneliassennl.jpg\",\"datePublished\":\"2022-06-20T17:19:31+00:00\",\"dateModified\":\"2025-11-27T12:59:40+00:00\",\"description\":\"Want to buy a metal windmill in a red color? View all of our garden stakes on the website or stop by our store. \u2713 Large collection \u2713 Good quality\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/windmill-hapiness-25cm-red-core\\\/#breadcrumb\"},\"inLanguage\":\"en-EN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/windmill-hapiness-25cm-red-core\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-EN\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/windmill-hapiness-25cm-red-core\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/windmolenhapiness25cmrodekerneliassennl.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/windmolenhapiness25cmrodekerneliassennl.jpg\",\"width\":726,\"height\":976,\"caption\":\"Windmill Hapiness 25cm red core - Eliassen.nl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/windmill-hapiness-25cm-red-core\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Garden plugs\",\"item\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/garden-plugs\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Windmills\",\"item\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/garden-plugs\\\/windmills\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Windmill Hapiness 25cm red core\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/\",\"name\":\"Eliassen Home & Garden Pleasure\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/#organization\"},\"alternateName\":\"Eliassen.nl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-EN\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/#organization\",\"name\":\"Eliassen Home & Garden Pleasure\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/windmill-hapiness-25cm-red-core\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/windmill-hapiness-25cm-red-core\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TuincentrumEliassenAmmerzoden\",\"https:\\\/\\\/www.instagram.com\\\/eliassenhomeandgarden\\\/\",\"https:\\\/\\\/nl.pinterest.com\\\/eliassenhomeandgarden\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@eliassenhomegardenpleasure4558\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-EN\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/windmill-hapiness-25cm-red-core\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo_4nd.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo_4nd.jpg\",\"width\":500,\"height\":500,\"caption\":\"Eliassen Home & Garden Pleasure\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"22.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"560223     rk\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Windmill Hapiness 25cm red core - Eliassen.nl","description":"Want to buy a metal windmill in a red color? View all of our garden stakes on the website or stop by our store. \u2713 Large collection \u2713 Good quality","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/","og_locale":"en_US","og_type":"article","og_title":"Other Windmill Hapiness 25cm red core - Eliassen.nl","og_description":"Want to buy a metal windmill in a red color? View all of our garden stakes on the website or stop by our store. \u2713 Large collection \u2713 Good quality","og_url":"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/","og_site_name":"Eliassen.nl","article_publisher":"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","article_modified_time":"2025-11-27T12:59:40+00:00","og_image":[{"width":726,"height":976,"url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/windmolenhapiness25cmrodekerneliassennl.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/","url":"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/","name":"Windmill Hapiness 25cm red core - Eliassen.nl","isPartOf":{"@id":"https:\/\/www.eliassen.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/#primaryimage"},"image":{"@id":"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/windmolenhapiness25cmrodekerneliassennl.jpg","datePublished":"2022-06-20T17:19:31+00:00","dateModified":"2025-11-27T12:59:40+00:00","description":"Want to buy a metal windmill in a red color? View all of our garden stakes on the website or stop by our store. \u2713 Large collection \u2713 Good quality","breadcrumb":{"@id":"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/#breadcrumb"},"inLanguage":"en-EN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/"]}]},{"@type":"ImageObject","inLanguage":"en-EN","@id":"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/#primaryimage","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/windmolenhapiness25cmrodekerneliassennl.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/windmolenhapiness25cmrodekerneliassennl.jpg","width":726,"height":976,"caption":"Windmill Hapiness 25cm red core - Eliassen.nl"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eliassen.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/www.eliassen.nl\/en\/store\/"},{"@type":"ListItem","position":3,"name":"Garden plugs","item":"https:\/\/www.eliassen.nl\/en\/garden-plugs\/"},{"@type":"ListItem","position":4,"name":"Windmills","item":"https:\/\/www.eliassen.nl\/en\/garden-plugs\/windmills\/"},{"@type":"ListItem","position":5,"name":"Windmill Hapiness 25cm red core"}]},{"@type":"WebSite","@id":"https:\/\/www.eliassen.nl\/en\/#website","url":"https:\/\/www.eliassen.nl\/en\/","name":"Eliassen Home & Garden Pleasure","description":"","publisher":{"@id":"https:\/\/www.eliassen.nl\/en\/#organization"},"alternateName":"Eliassen.nl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eliassen.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-EN"},{"@type":["Organization","Place"],"@id":"https:\/\/www.eliassen.nl\/en\/#organization","name":"Eliassen Home & Garden Pleasure","url":"https:\/\/www.eliassen.nl\/en\/","logo":{"@id":"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","https:\/\/www.instagram.com\/eliassenhomeandgarden\/","https:\/\/nl.pinterest.com\/eliassenhomeandgarden\/","https:\/\/www.youtube.com\/@eliassenhomegardenpleasure4558"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"en-EN","@id":"https:\/\/www.eliassen.nl\/en\/windmill-hapiness-25cm-red-core\/#local-main-organization-logo","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","width":500,"height":500,"caption":"Eliassen Home & Garden Pleasure"}]},"product_price_amount":"22.50","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"560223     rk","product_condition":"new"},"df_price":22.5,"df_sale_price":"","df_regular_price":22.5,"df_image_link":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/windmolenhapiness25cmrodekerneliassennl.jpg","image":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/windmolenhapiness25cmrodekerneliassennl.jpg","price_search":"<span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>&nbsp;22,50<\/bdi><\/span>","category":"Garden plugs","global_unique_id":"4025809059048","_links":{"self":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product\/72968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/media\/72965"}],"wp:attachment":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/media?parent=72968"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product_brand?post=72968"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product_cat?post=72968"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product_tag?post=72968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}