{"id":25019,"date":"2020-09-16T16:26:17","date_gmt":"2020-09-16T16:26:17","guid":{"rendered":"https:\/\/www.eliassen.nl\/?product=muurdeco-4-zeilboten"},"modified":"2026-01-16T13:50:32","modified_gmt":"2026-01-16T12:50:32","slug":"muurdeco-4-sailboats","status":"publish","type":"product","link":"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/","title":{"rendered":"Wall deco 4 Sailboats 81cm"},"content":{"rendered":"<p>This 3-dimensional metal wall decoration with the design of 4 sailboats, beautifully dresses up any modern interior or workplace. This attractive and timeless piece of wall decoration will be a real eye-catcher. Entirely handcrafted with polished parts giving the whole a distinct light play.<br \/>\nSince it is human-made, the photo may differ slightly from the real thing.<\/p>\n<p><strong>We have almost the entire collection of this series also in the store , which is unique in the Netherlands.<\/strong><br \/>\n<strong>Nowhere will you find such a large collection. You are most welcome.<\/strong><\/p>\n<ul>\n<li>  Size: 81cm wide, 50cm high, and 5cm deep<\/li>\n<li>  Material: Metal<\/li>\n<li>  Color: Various<\/li>\n<li>  Can be outdoors if protected<\/li>\n<li>  Easy to hang using 2 screws<\/li>\n<li>  Fast delivery<\/li>\n<li>  Largest collection in the Benelux that can also be viewed live.<\/li>\n<li>1 year warranty<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><strong>Outdoor use possible under shelter after treatment with clear varnish.<\/strong><\/p>\n","protected":false},"featured_media":25016,"template":"","meta":{"_acf_changed":false,"_genesis_title":"","_genesis_description":""},"product_brand":[7506],"product_cat":[513,510],"product_tag":[],"class_list":{"0":"post-25019","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-other","7":"product_cat-3d-wall-decoration-without-frame","8":"product_cat-wall-decoration","10":"first","11":"outofstock","12":"sale","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"meta_all":{"total_sales":"2","wcml_sync_hash":{"postmeta_fields":"69e7ef0e741158fd9b5c0602cb9278e3"},"attr_label_translations":[],"cor_restricted_countries":[]},"meta_all_flat":{"total_sales":"2","wcml_sync_hash.postmeta_fields":"69e7ef0e741158fd9b5c0602cb9278e3"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Wallco 4 Sailboats<\/title>\n<meta name=\"description\" content=\"Looking for a wall decoration? Order Wallco 4 Sailboats now. Wall decorations buy easily on our site. \u2713 Large selection \u2713 Fast delivery\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Other Wall deco 4 Sailboats 81cm - Eliassen.nl\" \/>\n<meta property=\"og:description\" content=\"Looking for a wall decoration? Order Wallco 4 Sailboats now. Wall decorations buy easily on our site. \u2713 Large selection \u2713 Fast delivery\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/\" \/>\n<meta property=\"og:site_name\" content=\"Eliassen.nl\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-16T12:50:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/eliassenmuurdeco4zeilboten.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1431\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/\",\"url\":\"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/\",\"name\":\"Wallco 4 Sailboats\",\"isPartOf\":{\"@id\":\"https:\/\/www.eliassen.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/eliassenmuurdeco4zeilboten.jpg\",\"datePublished\":\"2020-09-16T16:26:17+00:00\",\"dateModified\":\"2026-01-16T12:50:32+00:00\",\"description\":\"Looking for a wall decoration? Order Wallco 4 Sailboats now. Wall decorations buy easily on our site. \u2713 Large selection \u2713 Fast delivery\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#breadcrumb\"},\"inLanguage\":\"en-EN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-EN\",\"@id\":\"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#primaryimage\",\"url\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/eliassenmuurdeco4zeilboten.jpg\",\"contentUrl\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/eliassenmuurdeco4zeilboten.jpg\",\"width\":2048,\"height\":1431,\"caption\":\"Eliassen Muurdeco 4 Sailboats\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eliassen.nl\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\/\/www.eliassen.nl\/en\/store\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wall decoration\",\"item\":\"https:\/\/www.eliassen.nl\/en\/wall-decoration\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"3D Wall decoration without frame\",\"item\":\"https:\/\/www.eliassen.nl\/en\/wall-decoration\/3d-wall-decoration-without-frame\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Wall deco 4 Sailboats 81cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eliassen.nl\/en\/#website\",\"url\":\"https:\/\/www.eliassen.nl\/en\/\",\"name\":\"Eliassen Home & Garden Pleasure\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.eliassen.nl\/en\/#organization\"},\"alternateName\":\"Eliassen.nl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eliassen.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-EN\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/www.eliassen.nl\/en\/#organization\",\"name\":\"Eliassen Home & Garden Pleasure\",\"url\":\"https:\/\/www.eliassen.nl\/en\/\",\"logo\":{\"@id\":\"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden\",\"https:\/\/www.instagram.com\/eliassenhomeandgarden\/\",\"https:\/\/nl.pinterest.com\/eliassenhomeandgarden\/\",\"https:\/\/www.youtube.com\/@eliassenhomegardenpleasure4558\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-EN\",\"@id\":\"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#local-main-organization-logo\",\"url\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg\",\"contentUrl\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg\",\"width\":500,\"height\":500,\"caption\":\"Eliassen Home & Garden Pleasure\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"3.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"1478\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wallco 4 Sailboats","description":"Looking for a wall decoration? Order Wallco 4 Sailboats now. Wall decorations buy easily on our site. \u2713 Large selection \u2713 Fast delivery","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/","og_locale":"en_US","og_type":"article","og_title":"Other Wall deco 4 Sailboats 81cm - Eliassen.nl","og_description":"Looking for a wall decoration? Order Wallco 4 Sailboats now. Wall decorations buy easily on our site. \u2713 Large selection \u2713 Fast delivery","og_url":"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/","og_site_name":"Eliassen.nl","article_publisher":"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","article_modified_time":"2026-01-16T12:50:32+00:00","og_image":[{"width":2048,"height":1431,"url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/eliassenmuurdeco4zeilboten.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/","url":"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/","name":"Wallco 4 Sailboats","isPartOf":{"@id":"https:\/\/www.eliassen.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#primaryimage"},"image":{"@id":"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/eliassenmuurdeco4zeilboten.jpg","datePublished":"2020-09-16T16:26:17+00:00","dateModified":"2026-01-16T12:50:32+00:00","description":"Looking for a wall decoration? Order Wallco 4 Sailboats now. Wall decorations buy easily on our site. \u2713 Large selection \u2713 Fast delivery","breadcrumb":{"@id":"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#breadcrumb"},"inLanguage":"en-EN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/"]}]},{"@type":"ImageObject","inLanguage":"en-EN","@id":"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#primaryimage","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/eliassenmuurdeco4zeilboten.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/eliassenmuurdeco4zeilboten.jpg","width":2048,"height":1431,"caption":"Eliassen Muurdeco 4 Sailboats"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eliassen.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/www.eliassen.nl\/en\/store\/"},{"@type":"ListItem","position":3,"name":"Wall decoration","item":"https:\/\/www.eliassen.nl\/en\/wall-decoration\/"},{"@type":"ListItem","position":4,"name":"3D Wall decoration without frame","item":"https:\/\/www.eliassen.nl\/en\/wall-decoration\/3d-wall-decoration-without-frame\/"},{"@type":"ListItem","position":5,"name":"Wall deco 4 Sailboats 81cm"}]},{"@type":"WebSite","@id":"https:\/\/www.eliassen.nl\/en\/#website","url":"https:\/\/www.eliassen.nl\/en\/","name":"Eliassen Home & Garden Pleasure","description":"","publisher":{"@id":"https:\/\/www.eliassen.nl\/en\/#organization"},"alternateName":"Eliassen.nl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eliassen.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-EN"},{"@type":["Organization","Place"],"@id":"https:\/\/www.eliassen.nl\/en\/#organization","name":"Eliassen Home & Garden Pleasure","url":"https:\/\/www.eliassen.nl\/en\/","logo":{"@id":"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","https:\/\/www.instagram.com\/eliassenhomeandgarden\/","https:\/\/nl.pinterest.com\/eliassenhomeandgarden\/","https:\/\/www.youtube.com\/@eliassenhomegardenpleasure4558"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"en-EN","@id":"https:\/\/www.eliassen.nl\/en\/muurdeco-4-sailboats\/#local-main-organization-logo","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","width":500,"height":500,"caption":"Eliassen Home & Garden Pleasure"}]},"product_price_amount":"3.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"1478","product_condition":"new"},"df_price":3,"df_sale_price":3,"df_regular_price":64.5,"df_image_link":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/eliassenmuurdeco4zeilboten.jpg","image":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/eliassenmuurdeco4zeilboten.jpg","price_search":"<span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>&nbsp;3,00<\/bdi><\/span>","category":"3D Wall decoration without frame","global_unique_id":"9509686591211","_links":{"self":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product\/25019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/media\/25016"}],"wp:attachment":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/media?parent=25019"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product_brand?post=25019"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product_cat?post=25019"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product_tag?post=25019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}