{"id":158499,"date":"2024-07-24T19:32:53","date_gmt":"2024-07-24T19:32:53","guid":{"rendered":"https:\/\/www.eliassen.nl\/?product=kunstplant-met-lupine-bloemen-120cm-in-3-kleuren"},"modified":"2026-01-16T15:26:30","modified_gmt":"2026-01-16T14:26:30","slug":"kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2","status":"publish","type":"product","link":"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/","title":{"rendered":"Artificial plant lupine with purple flowers 120cm"},"content":{"rendered":"<p>Cozy up your garden, home or work environment with this beautiful large 120cm tall lupine with purple flowers.<\/p>\n<p>This true-to-nature model lupine with many purple flowers is made of the finest recycled plastic species, and stands well on its own because of the pot in which the plant stands. This large lupine fills empty spaces very quickly due to its height of as much as 120cm and many purple colored flowers. Combined with other silk plants, together in 1 large pot you can make a beautiful plant arrangement that you will not have to worry about.<\/p>\n<p>Are the plants too dry, or too wet, do they need fertilizer, is humidity right, all questions you no longer have to ask with these artificial plants. Wiping with a damp cloth occasionally is enough.<\/p>\n<p><strong>Virtually everything from artificial plants you can also view live with us !!!<\/strong><\/p>\n<p><strong>Order 3 artificial plants from us at once, and you get 10% discount !<\/strong><\/p>\n<ul>\n<li>Size: 120cm high<\/li>\n<li>Weight: approx 6kg<\/li>\n<li>Material: Recycled plastic, PVC free<\/li>\n<li>Color: green and purple<\/li>\n<li>Can also be set up outside, but in a shady place and not in full sunlight<\/li>\n<li>Warranty: 1 year<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>If you purchase more than 3 artificial plants, you will receive a 10% discount<\/p>\n","protected":false},"featured_media":158487,"template":"","meta":{"_acf_changed":false,"_genesis_title":"","_genesis_description":""},"product_brand":[7506],"product_cat":[7003],"product_tag":[],"class_list":["post-158499","product","type-product","status-publish","has-post-thumbnail","product_brand-other","product_cat-artificial-plants","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"meta_all":{"total_sales":"1","wcml_sync_hash":{"postmeta_fields":"5c589a46012e3aaae7937ef6aaf5c68c"},"attr_label_translations":[],"cor_restricted_countries":[],"cor_product_price_text_product_level":"","cor_add_text":"","cor_hide_r_add_cart_product_level":"1","cor_product_price_cart_btn_product_level":"","cor_replace_add_to_cart_custom_btn_product_level":"","enbility_product_level_disability":" ","enbility_product_level_exclude_visibility_rules":" "},"meta_all_flat":{"total_sales":"1","wcml_sync_hash.postmeta_fields":"5c589a46012e3aaae7937ef6aaf5c68c","cor_product_price_text_product_level":"","cor_add_text":"","cor_hide_r_add_cart_product_level":"1","cor_product_price_cart_btn_product_level":"","cor_replace_add_to_cart_custom_btn_product_level":"","enbility_product_level_disability":" ","enbility_product_level_exclude_visibility_rules":" "},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Artificial plant with lupine flowers 120cm in 3 colors<\/title>\n<meta name=\"description\" content=\"A beautiful, space-filling art lupine of high quality. A large artificial plant a a beautiful color. Fast delivery.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Other Artificial plant lupine with purple flowers 120cm - Eliassen.nl\" \/>\n<meta property=\"og:description\" content=\"A beautiful, space-filling art lupine of high quality. A large artificial plant a a beautiful color. Fast delivery.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Eliassen.nl\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-16T14:26:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/10\/kunstplantlupineeliassennl318000820.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"462\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\\\/\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\\\/\",\"name\":\"Artificial plant with lupine flowers 120cm in 3 colors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/kunstplantlupineeliassennl318000820.jpg\",\"datePublished\":\"2024-07-24T19:32:53+00:00\",\"dateModified\":\"2026-01-16T14:26:30+00:00\",\"description\":\"A beautiful, space-filling art lupine of high quality. A large artificial plant a a beautiful color. Fast delivery.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\\\/#breadcrumb\"},\"inLanguage\":\"en-EN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-EN\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/kunstplantlupineeliassennl318000820.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/kunstplantlupineeliassennl318000820.jpg\",\"width\":462,\"height\":1600,\"caption\":\"Artificial plant Lupine Eliassen.nl 318000820\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Artificial plants\",\"item\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/artificial-plants\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Artificial plant lupine with purple flowers 120cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/\",\"name\":\"Eliassen Home & Garden Pleasure\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/#organization\"},\"alternateName\":\"Eliassen.nl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-EN\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/#organization\",\"name\":\"Eliassen Home & Garden Pleasure\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TuincentrumEliassenAmmerzoden\",\"https:\\\/\\\/www.instagram.com\\\/eliassenhomeandgarden\\\/\",\"https:\\\/\\\/nl.pinterest.com\\\/eliassenhomeandgarden\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@eliassenhomegardenpleasure4558\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-EN\",\"@id\":\"https:\\\/\\\/www.eliassen.nl\\\/en\\\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo_4nd.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eliassen.nl\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo_4nd.jpg\",\"width\":500,\"height\":500,\"caption\":\"Eliassen Home & Garden Pleasure\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"59.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"318000820-1\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Artificial plant with lupine flowers 120cm in 3 colors","description":"A beautiful, space-filling art lupine of high quality. A large artificial plant a a beautiful color. Fast delivery.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/","og_locale":"en_US","og_type":"article","og_title":"Other Artificial plant lupine with purple flowers 120cm - Eliassen.nl","og_description":"A beautiful, space-filling art lupine of high quality. A large artificial plant a a beautiful color. Fast delivery.","og_url":"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/","og_site_name":"Eliassen.nl","article_publisher":"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","article_modified_time":"2026-01-16T14:26:30+00:00","og_image":[{"width":462,"height":1600,"url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/10\/kunstplantlupineeliassennl318000820.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/","url":"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/","name":"Artificial plant with lupine flowers 120cm in 3 colors","isPartOf":{"@id":"https:\/\/www.eliassen.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/#primaryimage"},"image":{"@id":"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/10\/kunstplantlupineeliassennl318000820.jpg","datePublished":"2024-07-24T19:32:53+00:00","dateModified":"2026-01-16T14:26:30+00:00","description":"A beautiful, space-filling art lupine of high quality. A large artificial plant a a beautiful color. Fast delivery.","breadcrumb":{"@id":"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/#breadcrumb"},"inLanguage":"en-EN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-EN","@id":"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/#primaryimage","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/10\/kunstplantlupineeliassennl318000820.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/10\/kunstplantlupineeliassennl318000820.jpg","width":462,"height":1600,"caption":"Artificial plant Lupine Eliassen.nl 318000820"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eliassen.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/www.eliassen.nl\/en\/store\/"},{"@type":"ListItem","position":3,"name":"Artificial plants","item":"https:\/\/www.eliassen.nl\/en\/artificial-plants\/"},{"@type":"ListItem","position":4,"name":"Artificial plant lupine with purple flowers 120cm"}]},{"@type":"WebSite","@id":"https:\/\/www.eliassen.nl\/en\/#website","url":"https:\/\/www.eliassen.nl\/en\/","name":"Eliassen Home & Garden Pleasure","description":"","publisher":{"@id":"https:\/\/www.eliassen.nl\/en\/#organization"},"alternateName":"Eliassen.nl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eliassen.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-EN"},{"@type":["Organization","Place"],"@id":"https:\/\/www.eliassen.nl\/en\/#organization","name":"Eliassen Home & Garden Pleasure","url":"https:\/\/www.eliassen.nl\/en\/","logo":{"@id":"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","https:\/\/www.instagram.com\/eliassenhomeandgarden\/","https:\/\/nl.pinterest.com\/eliassenhomeandgarden\/","https:\/\/www.youtube.com\/@eliassenhomegardenpleasure4558"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"en-EN","@id":"https:\/\/www.eliassen.nl\/en\/kunstplant-met-lupine-bloemen-120cm-in-3-kleuren-2\/#local-main-organization-logo","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","width":500,"height":500,"caption":"Eliassen Home & Garden Pleasure"}]},"product_price_amount":"59.50","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"318000820-1","product_condition":"new"},"df_price":59.5,"df_sale_price":"","df_regular_price":59.5,"df_image_link":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/10\/kunstplantlupineeliassennl318000820.jpg","image":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/10\/kunstplantlupineeliassennl318000820.jpg","price_search":"<span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>&nbsp;59,50<\/bdi><\/span>","category":"Artificial plants","global_unique_id":"6096519612616","_links":{"self":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product\/158499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/media\/158487"}],"wp:attachment":[{"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/media?parent=158499"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product_brand?post=158499"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product_cat?post=158499"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.eliassen.nl\/en\/wp-json\/wp\/v2\/product_tag?post=158499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}