{"id":78733,"date":"2022-11-29T14:31:27","date_gmt":"2022-11-29T14:31:27","guid":{"rendered":"https:\/\/www.eliassen.nl\/?product=tuinsteker-met-2-varkentjes-op-een-fiets"},"modified":"2025-11-26T17:40:47","modified_gmt":"2025-11-26T16:40:47","slug":"gartenstecker-mit-2-schweinen-auf-einem-fahrrad","status":"publish","type":"product","link":"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/","title":{"rendered":"Gartenstab mit 2 Schweinen auf einem Fahrrad"},"content":{"rendered":"<p>Werden Sie sich selbst oder jemand anderem mit diesem fr\u00f6hlichen Gartenhocker eine Freude machen?<br \/>Wundersch\u00f6n verarbeitetes Metallfahrrad mit 2 kleinen Schweinen darauf, das Sie \u00fcberall im Garten aufstellen k\u00f6nnen.  <br \/>Ein Blickfang in Ihrem Garten und eine tolle Geschenkidee. Vollst\u00e4ndig handgefertigt und bemalt.<br \/>Da es sich um ein handgefertigtes Produkt handelt, kann die Abbildung geringf\u00fcgig von einer echten Abbildung abweichen.<\/p>\n<p><strong>Wir haben fast alles aus dieser Serie im Ausstellungsraum, kommen Sie doch einfach vorbei und schauen Sie sich um.<\/strong><\/p>\n<ul>\n<li>Gr\u00f6\u00dfe 5x32x160 cm. hoch<\/li>\n<li>Schnelle Lieferung.<\/li>\n<li>100% handgefertigt.<\/li>\n<li>1 Jahr Garantie.<\/li>\n<\/ul>\n<p>Bitte beachten Sie, dass dieser Gartenstab nicht zum Aufstellen in vollem Wind geeignet ist und aufgrund der scharfen Kanten kein Spielzeug ist.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fr\u00f6hlicher Gartenstock mit 2 kleinen Schweinen auf einem Fahrrad.<\/p>\n","protected":false},"featured_media":78727,"template":"","meta":{"_acf_changed":false,"_genesis_title":"","_genesis_description":""},"product_brand":[7505],"product_cat":[836,845],"product_tag":[],"class_list":{"0":"post-78733","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-sonstige","7":"product_cat-gartenstecker","8":"product_cat-windmuehlen","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"meta_all":{"total_sales":"0","wcml_sync_hash":{"postmeta_fields":"debf9004eb5c1f0db0daa2a1a978f9b1"},"attr_label_translations":[]},"meta_all_flat":{"total_sales":"0","wcml_sync_hash.postmeta_fields":"debf9004eb5c1f0db0daa2a1a978f9b1"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gartenstab mit 2 Schweinen auf einem Fahrrad<\/title>\n<meta name=\"description\" content=\"Suchen Sie einen Gartenhocker? Bestellen Sie jetzt Gartenaufkleber Fahrrad mit 2 kleinen Schweinen. Kaufen Sie Gartendekorationen einfach auf unserer Website. Gro\u00dfe Auswahl \u2713 Schnelle Lieferung\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sonstige Gartenstab mit 2 Schweinen auf einem Fahrrad - Eliassen.nl\" \/>\n<meta property=\"og:description\" content=\"Suchen Sie einen Gartenhocker? Bestellen Sie jetzt Gartenaufkleber Fahrrad mit 2 kleinen Schweinen. Kaufen Sie Gartendekorationen einfach auf unserer Website. Gro\u00dfe Auswahl \u2713 Schnelle Lieferung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/\" \/>\n<meta property=\"og:site_name\" content=\"Eliassen.nl\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T16:40:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/tuinstekervarkentjeseliassennl.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/\",\"url\":\"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/\",\"name\":\"Gartenstab mit 2 Schweinen auf einem Fahrrad\",\"isPartOf\":{\"@id\":\"https:\/\/www.eliassen.nl\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/tuinstekervarkentjeseliassennl.jpg\",\"datePublished\":\"2022-11-29T14:31:27+00:00\",\"dateModified\":\"2025-11-26T16:40:47+00:00\",\"description\":\"Suchen Sie einen Gartenhocker? Bestellen Sie jetzt Gartenaufkleber Fahrrad mit 2 kleinen Schweinen. Kaufen Sie Gartendekorationen einfach auf unserer Website. Gro\u00dfe Auswahl \u2713 Schnelle Lieferung\",\"breadcrumb\":{\"@id\":\"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#primaryimage\",\"url\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/tuinstekervarkentjeseliassennl.jpg\",\"contentUrl\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/tuinstekervarkentjeseliassennl.jpg\",\"width\":1200,\"height\":900,\"caption\":\"Gartenstabschweine - eliassen.nl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.eliassen.nl\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.eliassen.nl\/de\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gartenstecker\",\"item\":\"https:\/\/www.eliassen.nl\/de\/gartenstecker\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Windm\u00fchlen\",\"item\":\"https:\/\/www.eliassen.nl\/de\/gartenstecker\/windmuehlen\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Gartenstab mit 2 Schweinen auf einem Fahrrad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.eliassen.nl\/de\/#website\",\"url\":\"https:\/\/www.eliassen.nl\/de\/\",\"name\":\"Eliassen Home & Garden Pleasure\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.eliassen.nl\/de\/#organization\"},\"alternateName\":\"Eliassen.nl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.eliassen.nl\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/www.eliassen.nl\/de\/#organization\",\"name\":\"Eliassen Home & Garden Pleasure\",\"url\":\"https:\/\/www.eliassen.nl\/de\/\",\"logo\":{\"@id\":\"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden\",\"https:\/\/www.instagram.com\/eliassenhomeandgarden\/\",\"https:\/\/nl.pinterest.com\/eliassenhomeandgarden\/\",\"https:\/\/www.youtube.com\/@eliassenhomegardenpleasure4558\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#local-main-organization-logo\",\"url\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg\",\"contentUrl\":\"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg\",\"width\":500,\"height\":500,\"caption\":\"Eliassen Home & Garden Pleasure\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"69.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"Md16210\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gartenstab mit 2 Schweinen auf einem Fahrrad","description":"Suchen Sie einen Gartenhocker? Bestellen Sie jetzt Gartenaufkleber Fahrrad mit 2 kleinen Schweinen. Kaufen Sie Gartendekorationen einfach auf unserer Website. Gro\u00dfe Auswahl \u2713 Schnelle Lieferung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/","og_locale":"de_DE","og_type":"article","og_title":"Sonstige Gartenstab mit 2 Schweinen auf einem Fahrrad - Eliassen.nl","og_description":"Suchen Sie einen Gartenhocker? Bestellen Sie jetzt Gartenaufkleber Fahrrad mit 2 kleinen Schweinen. Kaufen Sie Gartendekorationen einfach auf unserer Website. Gro\u00dfe Auswahl \u2713 Schnelle Lieferung","og_url":"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/","og_site_name":"Eliassen.nl","article_publisher":"https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","article_modified_time":"2025-11-26T16:40:47+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/tuinstekervarkentjeseliassennl.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/","url":"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/","name":"Gartenstab mit 2 Schweinen auf einem Fahrrad","isPartOf":{"@id":"https:\/\/www.eliassen.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#primaryimage"},"image":{"@id":"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/tuinstekervarkentjeseliassennl.jpg","datePublished":"2022-11-29T14:31:27+00:00","dateModified":"2025-11-26T16:40:47+00:00","description":"Suchen Sie einen Gartenhocker? Bestellen Sie jetzt Gartenaufkleber Fahrrad mit 2 kleinen Schweinen. Kaufen Sie Gartendekorationen einfach auf unserer Website. Gro\u00dfe Auswahl \u2713 Schnelle Lieferung","breadcrumb":{"@id":"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#primaryimage","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/tuinstekervarkentjeseliassennl.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/tuinstekervarkentjeseliassennl.jpg","width":1200,"height":900,"caption":"Gartenstabschweine - eliassen.nl"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eliassen.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.eliassen.nl\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Gartenstecker","item":"https:\/\/www.eliassen.nl\/de\/gartenstecker\/"},{"@type":"ListItem","position":4,"name":"Windm\u00fchlen","item":"https:\/\/www.eliassen.nl\/de\/gartenstecker\/windmuehlen\/"},{"@type":"ListItem","position":5,"name":"Gartenstab mit 2 Schweinen auf einem Fahrrad"}]},{"@type":"WebSite","@id":"https:\/\/www.eliassen.nl\/de\/#website","url":"https:\/\/www.eliassen.nl\/de\/","name":"Eliassen Home & Garden Pleasure","description":"","publisher":{"@id":"https:\/\/www.eliassen.nl\/de\/#organization"},"alternateName":"Eliassen.nl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eliassen.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","Place"],"@id":"https:\/\/www.eliassen.nl\/de\/#organization","name":"Eliassen Home & Garden Pleasure","url":"https:\/\/www.eliassen.nl\/de\/","logo":{"@id":"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/TuincentrumEliassenAmmerzoden","https:\/\/www.instagram.com\/eliassenhomeandgarden\/","https:\/\/nl.pinterest.com\/eliassenhomeandgarden\/","https:\/\/www.youtube.com\/@eliassenhomegardenpleasure4558"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.eliassen.nl\/de\/gartenstecker-mit-2-schweinen-auf-einem-fahrrad\/#local-main-organization-logo","url":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","contentUrl":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/logo_4nd.jpg","width":500,"height":500,"caption":"Eliassen Home & Garden Pleasure"}]},"product_price_amount":"69.50","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"Md16210","product_condition":"new"},"df_price":69.5,"df_sale_price":"","df_regular_price":69.5,"df_image_link":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/tuinstekervarkentjeseliassennl.jpg","image":"https:\/\/www.eliassen.nl\/wp-content\/uploads\/2024\/01\/tuinstekervarkentjeseliassennl.jpg","price_search":"<span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>&nbsp;69,50<\/bdi><\/span>","category":"Gartenstecker","global_unique_id":"5410807162101","_links":{"self":[{"href":"https:\/\/www.eliassen.nl\/de\/wp-json\/wp\/v2\/product\/78733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eliassen.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.eliassen.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eliassen.nl\/de\/wp-json\/wp\/v2\/media\/78727"}],"wp:attachment":[{"href":"https:\/\/www.eliassen.nl\/de\/wp-json\/wp\/v2\/media?parent=78733"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.eliassen.nl\/de\/wp-json\/wp\/v2\/product_brand?post=78733"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.eliassen.nl\/de\/wp-json\/wp\/v2\/product_cat?post=78733"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.eliassen.nl\/de\/wp-json\/wp\/v2\/product_tag?post=78733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}